{"id":628,"date":"2009-05-06T11:43:24","date_gmt":"2009-05-06T16:43:24","guid":{"rendered":"http:\/\/wpzoom.com\/zenko\/demo\/?page_id=3"},"modified":"2022-10-12T07:14:51","modified_gmt":"2022-10-12T07:14:51","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"628\" class=\"elementor elementor-628\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9a6140 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9a6140\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17c65841 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17c65841\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aba238e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3aba238e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c328179 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c328179\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43d70ba3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43d70ba3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17d0191f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17d0191f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-123b2e61\" data-id=\"123b2e61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a49ab5a elementor-widget elementor-widget-google_maps\" data-id=\"7a49ab5a\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Strada%201%20Decembrie%201918%2028%2C%20Deva%20330025&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Strada 1 Decembrie 1918 28, Deva 330025\"\n\t\t\t\t\taria-label=\"Strada 1 Decembrie 1918 28, Deva 330025\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6cbb87a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cbb87a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ed5f7b4\" data-id=\"2ed5f7b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d633110 elementor-widget elementor-widget-text-editor\" data-id=\"3d633110\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.7.8 - 02-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h4>ADDRESS<\/h4><p>Bld. 1 Decembrie 1918, Nr.28,<br \/>Jud. Hunedoara<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4d1e6ed3\" data-id=\"4d1e6ed3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f1a7e3e elementor-widget elementor-widget-text-editor\" data-id=\"1f1a7e3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4>CONTACT<\/h4><p>Email:\u00a0<a href=\"mailto:dgampth@gmail.com\">dgampth@gmail.com<\/a><\/p><p>Telefon: 0354 105 676<\/p><p>Fax: 0354 105 676<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d0f0609\" data-id=\"6d0f0609\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-248f1dd fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"248f1dd\" data-element_type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform fluentform_wrapper_3'><form data-form_id=\"3\" id=\"fluentform_3\" class=\"frm-fluent-form fluent_form_3 ff-el-form-top ff_form_instance_3_1 ff-form-loading\" data-form_instance=\"ff_form_instance_3_1\" method=\"POST\" action=\"\" ><input type='hidden' name='__fluent_form_embded_post_id' value='628' \/><input type=\"hidden\" id=\"_fluentform_3_fluentformnonce\" name=\"_fluentform_3_fluentformnonce\" value=\"283abf5bee\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/628\" \/><div data-type=\"name-element\" data-name=\"Nume\" class=\"ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group'><div class='ff-el-input--label asterisk-right'><label for='ff_3_Nume_first_name_'>First Name<\/label> <\/div><div class='ff-el-input--content'><input type=\"text\" name=\"Nume[first_name]\" id=\"ff_3_Nume_first_name_\" class=\"ff-el-form-control\" placeholder=\"First Name\" ><\/div><\/div><\/div><div class='ff-t-cell'><div class='ff-el-group'><div class='ff-el-input--label asterisk-right'><label for='ff_3_Nume_last_name_'>Name<\/label> <\/div><div class='ff-el-input--content'><input type=\"text\" name=\"Nume[last_name]\" id=\"ff_3_Nume_last_name_\" class=\"ff-el-form-control\" placeholder=\"Name\" ><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class='ff-el-input--label ff-el-is-required asterisk-right'><label for='ff_3_email'>Email<\/label> <\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_3_email\" class=\"ff-el-form-control\" placeholder=\"Email \" data-name=\"email\" ><\/div><\/div><div class='ff-el-group'><div class='ff-el-input--label ff-el-is-required asterisk-right'><label for='ff_3_subiect'>Subject<\/label> <\/div><div class='ff-el-input--content'><input type=\"text\" name=\"subiect\" class=\"ff-el-form-control\" placeholder=\"Subject\" data-name=\"subiect\" id=\"ff_3_subiect\" ><\/div><\/div><div class='ff-el-group'><div class='ff-el-input--label ff-el-is-required asterisk-right'><label for='ff_3_Mesaj'>Message<\/label> <\/div><div class='ff-el-input--content'><textarea name=\"Mesaj\" id=\"ff_3_Mesaj\" class=\"ff-el-form-control\" placeholder=\"Message\" rows=\"4\" cols=\"2\" data-name=\"Mesaj\" ><\/textarea><\/div><\/div><div class='ff-el-group    ff-el-input--content'><div class='ff-el-form-check ff-el-tc'><label class='ff-el-form-check-label ff_tc_label' for=\"terms-n-condition_d0659c484e0f652424a318680e53bf97\"><span class='ff_tc_checkbox'><input type=\"checkbox\" name=\"terms-n-condition\" class=\"ff-el-form-check-input\" data-name=\"terms-n-condition\" id=\"terms-n-condition_d0659c484e0f652424a318680e53bf97\"  value='on'><\/span> <div class='ff_t_c'>I have read and agree to the <a target=\"_blank\" rel=\"noopener\" href=\"#\">Terms and Conditions<\/a> and <a target=\"_blank\" rel=\"noopener\" href=\"#\">Privacy Policy<\/a><\/div><\/label><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\" >SEND <\/button><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><div id='fluentform_3_errors' class='ff-errors-in-stack ff_form_instance_3_1 ff-form-loading_errors ff_form_instance_3_1_errors'><\/div><\/div>        <script type=\"text\/javascript\">\n            window.fluent_form_ff_form_instance_3_1 = {\"id\":\"3\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"id\":\"39\",\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_3_1\",\"form_id_selector\":\"fluentform_3\",\"rules\":{\"Nume[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"Nume[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"Nume[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\"}},\"subiect\":{\"required\":{\"value\":true,\"message\":\"This field is required\"}},\"Mesaj\":{\"required\":{\"value\":true,\"message\":\"This field is required\"}},\"terms-n-condition\":{\"required\":{\"value\":false,\"message\":\"This field is required\"}}}};\n                    <\/script>\n                    <\/div>\n\n            \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ba82754 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ba82754\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ADRESA Bld. 1 Decembrie 1918, Nr.28,Jud. Hunedoara CONTACT Email:\u00a0dgampth@gmail.com Telefon: 0354 105 676 Fax: 0354 105 676 Prenume Nume Email Subiect Mesaj Trimite<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width-builder-bb.php","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-628","page","type-page","status-publish","hentry"],"ams_acf":[],"featured_media_urls":[],"_links":{"self":[{"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/pages\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":28,"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/pages\/628\/revisions"}],"predecessor-version":[{"id":7051,"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/pages\/628\/revisions\/7051"}],"wp:attachment":[{"href":"https:\/\/www.exploringdacia.absolutcontact.ro\/en\/wp-json\/wp\/v2\/media?parent=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}